{"id":3173,"date":"2016-02-08T15:54:18","date_gmt":"2016-02-08T15:54:18","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/deutsch\/?p=3173"},"modified":"2016-02-18T15:10:06","modified_gmt":"2016-02-18T15:10:06","slug":"der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/","title":{"rendered":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen"},"content":{"rendered":"<p>Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den Einzelhandelspreisindex (EHPI) gekoppelt, w\u00e4hrend sich die Bank of England am Verbraucherpreisindex (VPI) orientiert. Der Keil ist die Differenz zwischen diesen beiden Preisindizes und betr\u00e4gt Sch\u00e4tzungen zufolge langfristig rund 1%. Auf lange Sicht wird der EHPI \u2013 ganz grob gesehen \u2013 also etwa 1\u00a0% h\u00f6her sein als der VPI. Ursache dieses Keils ist die Tatsache, dass die Indizes auf unterschiedlichen Waren- und Dienstleistungsk\u00f6rben basieren, die unterschiedlich berechnet werden. Dazu kommt, dass man angesichts der deutlich h\u00f6heren Gewichtung von Wohnkosten (Immobilienpreise und Hypothekenzinsen) im EHPI vielleicht davon ausgehen sollte, dass der Keil noch breiter wird, wenn die Wohnimmobilienpreise weiter steigen oder es tats\u00e4chlich zu einer Zinserh\u00f6hung kommt.<\/p>\n<p>Eine \u00e4hnliche Keilentwicklung droht in den USA und zwar aus \u00e4hnlichem Grund wie in Gro\u00dfbritannien: TIPS sind an die Entwicklung des VPI gebunden, w\u00e4hrend sich die 2%-Zielmarke der Fed auf die privaten Konsumausgaben (PKA) bezieht. Auch hier basieren die zwei Indizes auf unterschiedlichen K\u00f6rben mit unterschiedlichen Gewichtungen, die unterschiedlich berechnet werden. Daher ergibt sich nur selten dieselbe Inflationsrate. In der Vergangenheit betrug dieser Keil in etwa ein viertel Prozent. Zu beachten ist dabei, dass die PKA die gesamten Ausgaben f\u00fcr den privaten Konsum messen, w\u00e4hrend der VPI die direkten Ausgaben der Haushalte messen soll.<\/p>\n<p>Es sieht so aus, als k\u00f6nnten die Wohn- und Gesundheitskosten den Keil zwischen VPI und PKA in nicht allzu ferner Zukunft \u00fcber den heutigen Wert von 0,1% steigen lassen. Dies h\u00e4ngt zum Teil mit dem Formeleffekt, aber auch mit den unterschiedlichen Gewichtungen in den beiden Indizes zusammen. So machen Wohnkosten 42% des VPI und lediglich 27% der PKA aus. Bei einem starken Immobilienmarkt mit geringer Leerstandsquote d\u00fcrfte der VPI daher schneller steigen als die PKA. Auch durch die Gesundheitskosten (6% des VPI gegen\u00fcber 22% der PKA) wird der Keil breiter, wenn auch auf eine andere Weise. Die Inflation der Gesundheitskosten d\u00fcrfte f\u00fcr mindestens die n\u00e4chsten 10 Jahren weiter auf einem sehr niedrigen Niveau bleiben, da die Preise f\u00fcr Gesundheitsprodukte und -leistungen im Rahmen der Programme Medicare und Medicaid festgelegt sind. Die im VPI erfassten Kosten f\u00fcr die medizinische Versorgung sind hingegen nicht staatlich geregelt und werden daher nicht so niedrig gehalten.<\/p>\n<p><a href=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png\" rel=\"attachment wp-att-3180\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3180\" src=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png\" alt=\"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen\" width=\"960\" height=\"720\" srcset=\"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png 960w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE-300x225.png 300w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>Anhand der Grafik wird deutlich, welche Signifikanz der Keil in Bezug auf die Kernpreise haben kann, wobei es so aussieht, als k\u00f6nnte er 0,8% oder m\u00f6glicherweise einen noch h\u00f6heren Wert erreichen. Als Anleiheninvestoren interessiert uns aber am meisten die Headline-Inflation. Diese bestimmt unseren Inflationsausgleich bei TIPS sowie das Inflationsziel der Fed. Nach Sch\u00e4tzungen von Morgan Stanley k\u00f6nnte der Headline-Keil aufgrund der unterschiedlichen Wohn- und Gesundheitskosten auf 0,5% anwachsen. Wenn Sie also so wie ich glauben, dass die Fed es mit ihrem Inflationsziel ernst meint, k\u00f6nnte der VPI bei einem PKA-Stand von 2% bei 2,5% liegen. F\u00fcr TIPS-Inhaber ist ein zus\u00e4tzlicher Inflationsausgleich von 25% eine durchweg feine Sache.<\/p>\n<p>In den USA scheint der Arbeitsmarkt derzeit angespannter zu sein als in Gro\u00dfbritannien und Europa: Das Angebot an Arbeitskr\u00e4ften ist knapper und die Wahrscheinlichkeit gr\u00f6\u00dfer, dass im Laufe dieses Jahres ein Lohnwachstum zu verzeichnen sein wird. Das ist einer der Gr\u00fcnde, weshalb Anleger TIPS gegen\u00fcber indexgebundenen Gilts oder europ\u00e4ischen Anleihen mit Inflationsschutz favorisieren k\u00f6nnten. Ein weiterer Grund f\u00fcr die Favorisierung von TIPS ist die Tatsache, dass die Basiseffekte der \u00d6lpreisentwicklung in den USA einen st\u00e4rkeren Abw\u00e4rtsdruck auf die Preise ausge\u00fcbt haben als in Gro\u00dfbritannien und Europa. Daher d\u00fcrften sie sich auch st\u00e4rker positiv auswirken, wenn sich der \u00d6lpreis stabilisiert oder gar steigt. Diese beiden Gr\u00fcnde zugunsten einer Anlage in TIPS k\u00f6nnen wir nun durch einen dritten erg\u00e4nzen: Damit die Fed ihr Inflationsziel von 2% erreicht, muss der VPI deutlich h\u00f6her steigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den Einzelhandelspreisindex (EHPI) gekoppelt, w\u00e4hrend sich die Bank of England am Verbraucherpreisindex (VPI) orientiert. Der Keil ist die Differenz zwischen diesen beiden Preisindizes und betr\u00e4gt Sch\u00e4tzungen zufolge langfristig rund 1%. Auf lange Sicht wird der EHPI \u2013 ganz grob gesehen \u2013 also etwa 1\u00a0% h\u00f6her sein als der VPI. Ursache dieses Keils ist die Tatsache, dass die Indizes auf unterschiedlichen Waren- und Dienstleistungsk\u00f6rben basieren, die&#8230;<\/p>\n","protected":false},"author":7,"featured_media":3180,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20,17],"tags":[233,212,232],"class_list":["post-3173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anleihenkategorien","category-inflation","tag-ehpi","tag-inflation","tag-vpi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen - Deutsch<\/title>\n<meta name=\"description\" content=\"Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ben Lord\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/\"},\"author\":{\"name\":\"Ben Lord\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/c4eecb682f956ed5d137f38e9a3137c1\"},\"headline\":\"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen\",\"datePublished\":\"2016-02-08T15:54:18+00:00\",\"dateModified\":\"2016-02-18T15:10:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/\"},\"wordCount\":654,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/new-wedge-in-us-inflation-linked-bonds-DE.png\",\"keywords\":[\"EHPI\",\"Inflation\",\"VPI\"],\"articleSection\":[\"Anleihenkategorien\",\"Inflation\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/\",\"name\":\"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/new-wedge-in-us-inflation-linked-bonds-DE.png\",\"datePublished\":\"2016-02-08T15:54:18+00:00\",\"dateModified\":\"2016-02-18T15:10:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/c4eecb682f956ed5d137f38e9a3137c1\"},\"description\":\"Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/new-wedge-in-us-inflation-linked-bonds-DE.png\",\"contentUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/new-wedge-in-us-inflation-linked-bonds-DE.png\",\"width\":960,\"height\":720,\"caption\":\"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2016\\\/02\\\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/\",\"name\":\"Deutsch\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/c4eecb682f956ed5d137f38e9a3137c1\",\"name\":\"Ben Lord\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g\",\"caption\":\"Ben Lord\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/author\\\/benlord\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen - Deutsch","description":"Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/","twitter_misc":{"Written by":"Ben Lord","Est. reading time":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/"},"author":{"name":"Ben Lord","@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/c4eecb682f956ed5d137f38e9a3137c1"},"headline":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen","datePublished":"2016-02-08T15:54:18+00:00","dateModified":"2016-02-18T15:10:06+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/"},"wordCount":654,"commentCount":0,"image":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png","keywords":["EHPI","Inflation","VPI"],"articleSection":["Anleihenkategorien","Inflation"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/","url":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/","name":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen - Deutsch","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#primaryimage"},"image":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png","datePublished":"2016-02-08T15:54:18+00:00","dateModified":"2016-02-18T15:10:06+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/c4eecb682f956ed5d137f38e9a3137c1"},"description":"Auf dem britischen Markt f\u00fcr Anleihen mit Inflationsbindung ist schon l\u00e4nger ein \u201eKeil\u201c zu beobachten: Diese Anleihen sind n\u00e4mlich an den","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#primaryimage","url":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png","contentUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/new-wedge-in-us-inflation-linked-bonds-DE.png","width":960,"height":720,"caption":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen"},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/deutsch\/2016\/02\/der-neue-keil-auf-dem-markt-fur-inflationsgebundene-us-anleihen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bondvigilantes.com\/deutsch\/"},{"@type":"ListItem","position":2,"name":"Der neue Keil auf dem Markt f\u00fcr inflationsgebundene US-Anleihen"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/deutsch\/#website","url":"https:\/\/bondvigilantes.com\/deutsch\/","name":"Deutsch","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/deutsch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/c4eecb682f956ed5d137f38e9a3137c1","name":"Ben Lord","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae49b7b375d8db374c66cb0562a292304e64de9f1a05bb7c893c987f4f154110?s=96&d=mm&r=g","caption":"Ben Lord"},"url":"https:\/\/bondvigilantes.com\/deutsch\/author\/benlord\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts\/3173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/comments?post=3173"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts\/3173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/media\/3180"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/media?parent=3173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/categories?post=3173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/tags?post=3173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}