{"id":5243,"date":"2020-07-02T07:34:00","date_gmt":"2020-07-02T07:34:00","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/deutsch\/?p=5243"},"modified":"2021-12-03T15:10:28","modified_gmt":"2021-12-03T15:10:28","slug":"qe-erobert-die-welt","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/","title":{"rendered":"QE erobert die Welt"},"content":{"rendered":"\r\n<p>Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage waren, ihre Wirtschaft in Krisenzeiten geldpolitisch so anzukurbeln wie die Industriestaaten. In der Regel mussten sie die Zinsen erh\u00f6hen, um die Kapitalabfl\u00fcsse zu begrenzen und ihre W\u00e4hrungen zu verteidigen, wodurch die wirtschaftliche Erholung erschwert wurde.<\/p>\r\n\r\n\r\n\r\n<p>Deshalb ist es besonders interessant zu beobachten, was die Schwellenl\u00e4nder w\u00e4hrend der Coronakrise, die gerade \u00fcber die Welt hereingebrochen ist, getan haben. Die meisten Zentralbanken der Schwellenl\u00e4nder haben ihre Politik gelockert, indem sie die Zinsen zum Teil recht aggressiv gesenkt haben (siehe Grafik unten), und ich glaube, es k\u00f6nnte noch Luft f\u00fcr weitere Zinssenkungen geben. Dies ist eine sehr willkommene Entwicklung, die dazu beitragen wird, die Konjunktur in diesen schwierigen Zeiten zu unterst\u00fctzen. Dies gilt umso mehr, als die lokale Finanzierung in vielen Schwellenl\u00e4ndern, die sich fr\u00fcher \u00fcberwiegend in Fremdw\u00e4hrungen verschuldet haben, allm\u00e4hlich an Bedeutung gewonnen hat, wie zum Beispiel in Brasilien. Obwohl viele Schwellenl\u00e4nderw\u00e4hrungen in der Anfangsphase der Krise stark eingebrochen sind, haben sich die meisten seither trotz dieser Einschnitte deutlich erholt. Einer der Hauptgr\u00fcnde f\u00fcr diese Entwicklung ist die niedrige Inflation, die wir zuletzt in den meisten Schwellenl\u00e4ndern gesehen haben, und die Erwartung, dass die Inflation in naher Zukunft niedrig bleiben d\u00fcrfte, da die Nachfrage im Zuge der Pandemie zusammengebrochen ist. Besonders hilfreich war auch die Tatsache, dass die Fed die Zinsen auf nahezu Null gesenkt hat.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" class=\"wp-image-5245\" src=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png\" alt=\"\" srcset=\"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png 960w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global-300x225.png 300w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>Dies hat zwar dazu gef\u00fchrt, dass die Zinsen in den Schwellenl\u00e4ndern auf historische Tiefst\u00e4nde gesunken sind, was die W\u00e4hrungen der Schwellenl\u00e4nder m\u00f6glicherweise schw\u00e4cht, doch die Differenz zwischen den Zinsen in den Schwellenl\u00e4ndern und den Zinsen in den Industriestaaten ist nach wie vor gro\u00df. Die meisten Realzinsen in den Schwellenl\u00e4ndern liegen (im Gegensatz zu den Zinsen in den Industriestaaten) immer noch im positiven Bereich. Meiner Ansicht nach sind die Schwellenl\u00e4nder daher nach wie vor ein Marktbereich, in dem renditeorientierte Anleger f\u00fcndig werden sollten.<\/p>\r\n\r\n\r\n\r\n<p>Vielleicht noch \u00fcberraschender ist, dass mehrere Zentralbanken der Schwellenl\u00e4nder Staatsanleihen gekauft haben, auch bekannt als Quantitative Easing (QE), ein Instrument, das bisher nur von den gro\u00dfen Zentralbanken der Industriel\u00e4nder genutzt wurde (weitere Einzelheiten finden Sie in der nachstehenden Tabelle). Der Umfang dieser K\u00e4ufe ist vermutlich immer noch deutlich geringer als in den Industriel\u00e4ndern und betr\u00e4gt in den meisten F\u00e4llen weniger als 2% des BIP. Die Zentralbanken in den Schwellenl\u00e4ndern haben nach wie vor kleinere Bilanzen als in den Industriel\u00e4ndern, und diejenigen mit gro\u00dfen Bilanzen haben in der Regel eher hohe Devisenreserven als staatliche Verm\u00f6genswerte. Ein weiterer wichtiger Unterschied besteht darin, dass die Zentralbanken in den Schwellenl\u00e4ndern bei der Festlegung der Zinss\u00e4tze f\u00fcr gew\u00f6hnlich nicht die Nullmarke erreichen, und die meisten d\u00fcrften dazu kaum in der Lage sein. Dies wirft die Frage nach der relativen Wirksamkeit der quantitativen Lockerung auf, da die konventionelle Geldpolitik noch nicht ausgesch\u00f6pft ist.<\/p>\r\n\r\n\r\n\r\n<p>Bislang haben die meisten Zentralbanken der Schwellenl\u00e4nder die quantitative Lockerung durch den Kauf von Staatsanleihen auf dem Sekund\u00e4rmarkt und nicht auf dem Prim\u00e4rmarkt umgesetzt.\u00a0Obwohl man behaupten kann, dass das Endergebnis sehr \u00e4hnlich ist, kann der Kauf \u00fcber den Sekund\u00e4rmarkt die Bedenken zerstreuen, dass die Zentralbanken der Schwellenl\u00e4nder die Staatsdefizite direkt finanzieren. Stattdessen kann es als Ma\u00dfnahme angesehen werden, die darauf abzielt, den Markt in einer Stressphase mit Liquidit\u00e4t und Unterst\u00fctzung zu versorgen.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" class=\"wp-image-5246\" src=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/3\/2021\/12\/2-de-37_QE-goes-global.png\" alt=\"\" srcset=\"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/2-de-37_QE-goes-global.png 960w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/2-de-37_QE-goes-global-300x225.png 300w, https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/2-de-37_QE-goes-global-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>Die meisten L\u00e4nder, die sich in Sachen QE engagiert haben, profitieren von einer relativ hohen Bonit\u00e4t (die Mehrheit hat ein Investment-Grade-Rating) und haben ihre lokalen M\u00e4rkte weiterentwickelt, wodurch sie an Glaubw\u00fcrdigkeit bei der Festlegung ihrer Finanz- und Geldpolitik gewonnen haben. Das Vorgehen einiger L\u00e4nder, wie z. B. S\u00fcdafrika und der T\u00fcrkei, die ebenfalls Verm\u00f6genswerte aufkaufen, aber bereits unter mangelnder Glaubw\u00fcrdigkeit und Fragen zur Unabh\u00e4ngigkeit der Zentralbank leiden, k\u00f6nnte l\u00e4ngerfristig weitere Fragen bei den Investoren aufwerfen.<\/p>\r\n\r\n\r\n\r\n<p>Wenn man bedenkt, wie au\u00dfergew\u00f6hnlich die aktuelle Krise ist, hat sich dieser Impuls als sehr hilfreich f\u00fcr die Unterst\u00fctzung der lokalen M\u00e4rkte erwiesen. QE k\u00f6nnte kurzfristig ein wichtiges Instrument sein, um die steigenden Haushaltsdefizite infolge der Krise zu finanzieren. Letzten Endes kann QE aber auch als eine Form des Gelddruckens gesehen werden. Dies k\u00f6nnte auf l\u00e4ngere Sicht problematisch werden, wenn die Anleger der Meinung sind, dass die L\u00e4nder damit eine Alternative zur Haushaltsdisziplin schaffen. Wenn der Markt das Vertrauen verliert, k\u00f6nnte dies zu erheblichen Abfl\u00fcssen aus den lokalen M\u00e4rkten f\u00fchren, was wiederum eine potenzielle W\u00e4hrungsabwertung und eine importierte Inflation anheizt. Die Tatsache, dass sich der Ankauf von Verm\u00f6genswerten seit M\u00e4rz aufgrund der Marktstabilisierung und der Erholung der Verm\u00f6genspreise in den meisten L\u00e4ndern verlangsamt hat, ist ein positives Zeichen \u2013 ebenso wie die Tatsache, dass die Schwellenl\u00e4nder in den letzten zwei Monaten in der Lage waren, betr\u00e4chtliche Mengen an lokalen Anleihen zu emittieren. Wie einfach ein Kurswechsel sein wird, bleibt jedoch offen, und die Erfahrungen der Industriestaaten beim Ausstieg aus QE sind kein besonders ermutigendes Vorbild.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage waren, ihre Wirtschaft in Krisenzeiten geldpolitisch so anzukurbeln wie die Industriestaaten. In der Regel mussten sie die Zinsen erh\u00f6hen, um die Kapitalabfl\u00fcsse zu begrenzen und ihre W\u00e4hrungen zu verteidigen, wodurch die wirtschaftliche Erholung erschwert wurde. Deshalb ist es besonders interessant zu beobachten, was die Schwellenl\u00e4nder w\u00e4hrend der Coronakrise, die gerade \u00fcber die Welt hereingebrochen ist, getan haben. Die meisten Zentralbanken der Schwellenl\u00e4nder haben ihre Politik&#8230;<\/p>\n","protected":false},"author":165,"featured_media":5245,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[287],"tags":[],"class_list":["post-5243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schwellenlaender"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>QE erobert die Welt - Deutsch<\/title>\n<meta name=\"description\" content=\"Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexis Duvernay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/\"},\"author\":{\"name\":\"Alexis Duvernay\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/105ee8decb3920960612d5490a14c86f\"},\"headline\":\"QE erobert die Welt\",\"datePublished\":\"2020-07-02T07:34:00+00:00\",\"dateModified\":\"2021-12-03T15:10:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/\"},\"wordCount\":876,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/1-de-37_QE-goes-global.png\",\"articleSection\":[\"Schwellenl\u00e4nder\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/\",\"name\":\"QE erobert die Welt - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/1-de-37_QE-goes-global.png\",\"datePublished\":\"2020-07-02T07:34:00+00:00\",\"dateModified\":\"2021-12-03T15:10:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/105ee8decb3920960612d5490a14c86f\"},\"description\":\"Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/1-de-37_QE-goes-global.png\",\"contentUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/1-de-37_QE-goes-global.png\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/2020\\\/07\\\/qe-erobert-die-welt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QE erobert die Welt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/\",\"name\":\"Deutsch\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/#\\\/schema\\\/person\\\/105ee8decb3920960612d5490a14c86f\",\"name\":\"Alexis Duvernay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g\",\"caption\":\"Alexis Duvernay\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/deutsch\\\/author\\\/alexisduvernay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"QE erobert die Welt - Deutsch","description":"Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/","twitter_misc":{"Written by":"Alexis Duvernay","Est. reading time":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/"},"author":{"name":"Alexis Duvernay","@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/105ee8decb3920960612d5490a14c86f"},"headline":"QE erobert die Welt","datePublished":"2020-07-02T07:34:00+00:00","dateModified":"2021-12-03T15:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/"},"wordCount":876,"commentCount":0,"image":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png","articleSection":["Schwellenl\u00e4nder"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/","url":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/","name":"QE erobert die Welt - Deutsch","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#primaryimage"},"image":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png","datePublished":"2020-07-02T07:34:00+00:00","dateModified":"2021-12-03T15:10:28+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/105ee8decb3920960612d5490a14c86f"},"description":"Historisch gesehen bestand eines der charakteristischen Merkmale der Volkswirtschaften der Schwellenl\u00e4nder (EM) darin, dass sie generell nicht in der Lage","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#primaryimage","url":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png","contentUrl":"https:\/\/bondvigilantes.com\/deutsch\/wp-content\/uploads\/sites\/3\/2021\/12\/1-de-37_QE-goes-global.png","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/deutsch\/2020\/07\/qe-erobert-die-welt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bondvigilantes.com\/deutsch\/"},{"@type":"ListItem","position":2,"name":"QE erobert die Welt"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/deutsch\/#website","url":"https:\/\/bondvigilantes.com\/deutsch\/","name":"Deutsch","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/deutsch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/deutsch\/#\/schema\/person\/105ee8decb3920960612d5490a14c86f","name":"Alexis Duvernay","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08777aa16121c3255144412a68255b4927fd8ad88530cfdf4a3aee50e4b0cf86?s=96&d=mm&r=g","caption":"Alexis Duvernay"},"url":"https:\/\/bondvigilantes.com\/deutsch\/author\/alexisduvernay\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts\/5243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/comments?post=5243"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/posts\/5243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/media\/5245"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/media?parent=5243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/categories?post=5243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/deutsch\/wp-json\/wp\/v2\/tags?post=5243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}