{"id":1659,"date":"2016-07-20T15:24:31","date_gmt":"2016-07-20T15:24:31","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/francais\/?p=1659"},"modified":"2023-09-04T15:59:14","modified_gmt":"2023-09-04T15:59:14","slug":"le-marche-des-obligations-perpetuelles-bresiliennes","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/","title":{"rendered":"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&rsquo;est pas correctement \u00e9valu\u00e9"},"content":{"rendered":"\n<p>Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation relative \u00e0 ces titres stipule que ces derniers pr\u00e9sentent un rang de priorit\u00e9 inf\u00e9rieur \u00e0 toute autre dette de premier rang (garantie ou non). En cons\u00e9quence, ces titres ont tendance \u00e0 \u00eatre moins bien not\u00e9s que les obligations de premier rang log\u00e9es dans la m\u00eame structure de capital, la probabilit\u00e9 de recouvrement du capital investi \u00e9tant jug\u00e9e plus faible. Dans les march\u00e9s \u00e9mergents toutefois, il n&rsquo;est pas rare de voir des obligations perp\u00e9tuelles de premier rang non garanties. Afin de s\u00e9curiser leur financement \u00e0 long terme, des entreprises br\u00e9siliennes, comme la soci\u00e9t\u00e9 de construction Odebrecht ou la compagnie a\u00e9rienne nationale <a href=\"https:\/\/ri.voegol.com.br\/\" target=\"_blank\" rel=\"noopener\"><strong>GOL<\/strong><\/a>, ont \u00e9mis des obligations perp\u00e9tuelles au cours de la derni\u00e8re d\u00e9cennie, encourag\u00e9es en cela par la qu\u00eate de rendement des investisseurs. Dans la plupart des cas, une clause contractuelle <em>pari passu<\/em> permet de hisser ces obligations perp\u00e9tuelles au m\u00eame rang de priorit\u00e9 que les autres cr\u00e9ances non garanties et non subordonn\u00e9es du m\u00eame \u00e9metteur. Il existe cependant un point commun entre les march\u00e9s d\u00e9velopp\u00e9s et leurs homologues \u00e9mergents : le statut de dette s\u00e9nior et le rang de priorit\u00e9 d&rsquo;une obligation ne d\u00e9pendent pas de sa maturit\u00e9. Ainsi, deux obligations non garanties de premier rang, ayant des maturit\u00e9s diff\u00e9rentes mais une documentation commune, se verront attribuer la m\u00eame notation de cr\u00e9dit.<\/p>\n\n\n\n<p>L&rsquo;\u00e9metteur GOL constitue un cas typique : la compagnie a\u00e9rienne br\u00e9silienne a \u00e9mis en 2006 pour 200 millions de dollars d&rsquo;obligations perp\u00e9tuelles (GOLLBZ 8,75 %). Cette obligation pr\u00e9sentait un rang de priorit\u00e9 et des nantissements* similaires \u00e0 l&rsquo;\u00e9mission longue de maturit\u00e9 fixe GOLLBZ 7,5&nbsp;% 2017, titre de premier rang non garanti. En cons\u00e9quence, les agences de notation ont attribu\u00e9 en 2007 une notation de cr\u00e9dit \u00e9quivalente aux deux instruments (Ba2 chez Moody&rsquo;s, et BB+ chez Fitch), faisant l&rsquo;hypoth\u00e8se que leurs probabilit\u00e9s de d\u00e9faut et de recouvrement de valeur seraient similaires. Sur le papier, cela semblait raisonnable, le droit br\u00e9silien en mati\u00e8re de restructuration stipulant que les cr\u00e9anciers d&rsquo;une m\u00eame cat\u00e9gorie doivent \u00eatre trait\u00e9s sur un pied d&rsquo;\u00e9galit\u00e9. Le ralentissement \u00e9conomique au Br\u00e9sil a cependant d\u00e9montr\u00e9, de mon point de vue, que cette approche s&rsquo;av\u00e9rait en fait moins prudente pour les investisseurs obligataires.<\/p>\n\n\n\n<p>A partir de 2012, la GOL a d\u00fb faire face \u00e0 d&rsquo;importantes turbulences macro\u00e9conomiques (r\u00e9cession et d\u00e9pr\u00e9ciation de la devise), ce qui a entra\u00een\u00e9 une diminution de la demande, des surcapacit\u00e9s dans l&rsquo;industrie, et des difficult\u00e9s financi\u00e8res pour l&rsquo;une des plus importantes compagnies a\u00e9riennes br\u00e9siliennes. Les agences de notation ont alors d\u00e9grad\u00e9 les obligations \u00e9mises par la GOL afin de refl\u00e9ter la d\u00e9t\u00e9rioration de son profil de cr\u00e9dit. Les obligations perp\u00e9tuelles non garanties retrouv\u00e8rent alors des notations proches de celles d&rsquo;autres obligations non garanties de maturit\u00e9 fixe. En mai 2016, le niveau de tr\u00e9sorerie et la structure du bilan de la GOL devinrent insoutenables, et l&rsquo;entreprise se r\u00e9signa \u00e0 lancer une offre de restructuration. La restructuration priv\u00e9e permettait aux porteurs obligataires d&rsquo;\u00e9changer leurs obligations existantes contre une petite partie en num\u00e9raire et des obligations nouvellement \u00e9mises. Cependant, alors que les obligations non garanties de premier rang d&rsquo;\u00e9ch\u00e9ance entre 2020 et 2023 ont toutes \u00e9t\u00e9 trait\u00e9es sur un pied d&rsquo;\u00e9galit\u00e9 (la proposition impliquait une d\u00e9cote d&rsquo;environ 45&nbsp;% au mieux sur la dette), les d\u00e9tenteurs d&rsquo;obligations perp\u00e9tuelles non garanties de premier rang se voyaient proposer des conditions bien moins favorables : une d\u00e9cote de 55 % et un transfert complet vers les nouvelles obligations, sans aucune compensation en num\u00e9raire.<\/p>\n\n\n\n<p>Les porteurs de l&rsquo;obligation la plus courte (GOLLBZ 7,5 % \u00e9ch\u00e9ance 2017) re\u00e7urent le meilleur traitement et ne subirent qu&rsquo;une d\u00e9cote de 30 % environ sur cette dette. M\u00eame la commission de participation initiale accord\u00e9e aux d\u00e9tenteurs d&rsquo;obligations pour avoir accept\u00e9 l&rsquo;offre \u00e9tait moins attractive pour les obligations perp\u00e9tuelles (aucun versement en num\u00e9raire). En cons\u00e9quence, les montants recouvr\u00e9s sur les obligations perp\u00e9tuelles furent inf\u00e9rieurs \u00e0 ceux des obligations non garanties de premier rang. En cela, l&rsquo;offre de restructuration n&rsquo;a respect\u00e9 ni le rang ni les garanties contractuelles des diff\u00e9rentes obligations, mais a plut\u00f4t traiter les \u00e9missions en fonction de leurs \u00e9ch\u00e9ances.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png\" data-rel=\"lightbox-gallery-zZ7CB1F2\" data-rl_title=\"basil-prep1\" data-rl_caption=\"basil-prep1\" title=\"basil-prep1\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png\" alt=\"\" class=\"wp-image-6049\" srcset=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png 960w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1-300x225.png 300w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Les agences de notation semblent ne pas avoir tenu compte de ce qui pr\u00e9c\u00e8de, m\u00eame si c&rsquo;\u00e9tait de toute fa\u00e7on trop tard pour les porteurs d&rsquo;obligations. Le 5 mai 2016, quelques jours apr\u00e8s l&rsquo;annonce de l&rsquo;offre d&rsquo;\u00e9change par la GOL, Moody&rsquo;s <a href=\"https:\/\/www.moodys.com\/research\/Moodys-downgrades-Gol-Linhas-Aereass-ratings-with-planned-debt-exchange--PR_348372\" target=\"_blank\" rel=\"noopener\"><strong>changea d&rsquo;avis<\/strong><\/a> et d\u00e9cida de d\u00e9grader l&rsquo;obligation perp\u00e9tuelle de Caa2 \u00e0 C. Dans le m\u00eame temps, l&rsquo;obligation d&rsquo;\u00e9ch\u00e9ance fixe 2017 ne fut d\u00e9grad\u00e9e que d&rsquo;un seul cran, passant de Caa3 de Caa2. Moody&rsquo;s notait \u00e0 cette occasion&nbsp;: <em>\u00ab&nbsp;L&rsquo;obligation non garantie de premier rang et d&rsquo;\u00e9ch\u00e9ance 2017 est maintenant not\u00e9e au m\u00eame niveau (que la soci\u00e9t\u00e9 \u00e9mettrice), \u00e9tant donn\u00e9 son taux de recouvrement anticip\u00e9. De son c\u00f4t\u00e9, l&rsquo;obligation perp\u00e9tuelle est d\u00e9sormais not\u00e9e C, compte tenu de son plus faible taux de recouvrement anticip\u00e9.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p>Le cas de la GOL a des cons\u00e9quences importantes pour le reste du march\u00e9 br\u00e9silien des dettes perp\u00e9tuelles, march\u00e9 qui me para\u00eet d\u00e9sormais trop cher et surc\u00f4t\u00e9. En g\u00e9n\u00e9ral, dans un monde non \u00ab&nbsp;distressed&nbsp;\u00bb, les spreads moyens pour d\u00e9tenir des obligations perp\u00e9tuelles au Br\u00e9sil se situent entre 50 et 200 points de base au-dessus des obligations non garanties de premier rang \u00e0 10 ans. Mais ce spread r\u00e9mun\u00e8re la diff\u00e9rence de maturit\u00e9 (l&rsquo;incertitude entourant de date \u00e0 laquelle les porteurs d&rsquo;obligations seront rembours\u00e9s), plut\u00f4t que la valeur de recouvrement estim\u00e9e. Cela s&rsquo;explique peut-\u00eatre car la plupart des obligations perp\u00e9tuelles continuent de b\u00e9n\u00e9ficier de notations similaires \u00e0 celles des obligations non garanties \u00e0 \u00e9ch\u00e9ance fixe. Par exemple, c&rsquo;est le cas des obligations perp\u00e9tuelles de la soci\u00e9t\u00e9 p\u00e9trochimique Braskem (Ba1) : ces titres se traitent actuellement avec un spread de 48 points de base par rapport aux obligations non garanties d&rsquo;\u00e9ch\u00e9ance 2024 du m\u00eame \u00e9metteur (Ba1).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep2.png\" data-rel=\"lightbox-gallery-zZ7CB1F2\" data-rl_title=\"basil-prep2\" data-rl_caption=\"basil-prep2\" title=\"basil-prep2\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep2.png\" alt=\"\" class=\"wp-image-6050\" srcset=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep2.png 960w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep2-300x225.png 300w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep2-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>S&rsquo;agissant du cr\u00e9dit \u00ab&nbsp;distressed&nbsp;\u00bb (\u00e9metteurs en difficult\u00e9), certaines obligations perp\u00e9tuelles se n\u00e9gocient m\u00eame \u00e0 des prix au comptant plus \u00e9lev\u00e9s que ceux des obligations non garanties de premier rang \u00e0 \u00e9ch\u00e9ance fixe, titres pourtant issus de la m\u00eame structure de capital. Les obligations perp\u00e9tuelles \u00e9mises par l&rsquo;entreprise de construction Odebrecht (B2, perspective n\u00e9gative) se traitent sur un spread moyen de 48 point de base, tandis que les obligations Odebrecht non garanties de maturit\u00e9 2025 (BA2, perspective n\u00e9gative) se n\u00e9gocient sur un niveau de 40 points de base. Cela n&rsquo;a pas beaucoup de sens. Je me demande toujours si les investisseurs ont int\u00e9gr\u00e9 le fait suivant : m\u00eame si sur le papier, ces instruments b\u00e9n\u00e9ficient d&rsquo;<em>un m\u00eame rang de priorit\u00e9<\/em> que les autres obligations non garanties, dans la pratique, ils risquent d&rsquo;\u00eatre trait\u00e9s diff\u00e9remment \u00e0 l&rsquo;occasion d&rsquo;une restructuration priv\u00e9e.<\/p>\n\n\n\n<p>Les porteurs avis\u00e9s d&rsquo;obligations perp\u00e9tuelles br\u00e9siliennes pourraient vouloir faire baisser d&rsquo;un cran la notation de leurs titres en interne, et s&rsquo;assurer qu&rsquo;ils seront bien r\u00e9mun\u00e9r\u00e9s pour le risque qu&rsquo;ils prennent. Cela pourrait s&rsquo;av\u00e9rer particuli\u00e8rement utile dans un pays o\u00f9 les taux de d\u00e9faut et la probabilit\u00e9 de restructurations de dettes priv\u00e9es sur les prochains 12 \u00e0 18 mois sont \u00e9lev\u00e9s.<\/p>\n\n\n\n<p><span style=\"font-size: small\">* La documentation relative \u00e0 l&rsquo;obligation stipule : Les obligations ne seront pas garanties et auront le m\u00eame rang que les autres cr\u00e9ances non subordonn\u00e9es et non garanties que l&rsquo;Emetteur pourrait supporter. Les obligations seront nanties, conjointement et solidairement, sur une base non subordonn\u00e9e et non garantie par les Garants.<\/span><\/p>\n\n\n\n<p><span style=\"font-size: small\">Les nantissements auront le m\u00eame rang au droit de paiement que les autres cr\u00e9ances non garanties et non subordonn\u00e9es, et que les autres nantissements accord\u00e9s par les Garants. Les obligations auront dans les faits un rang de priorit\u00e9 inf\u00e9rieur aux cr\u00e9ances garanties de l&rsquo;Emetteur et des Garants. En vertu de la loi br\u00e9silienne, les porteurs d&rsquo;obligations n&rsquo;auront aucun recours contre les filiales non garantes des Garants. Les Garants garantiront inconditionnellement, conjointement et solidairement, sur une base non subordonn\u00e9es et non s\u00e9curis\u00e9e, toutes les obligations de l&rsquo;Emetteur en vertu de ces notes.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation relative \u00e0 ces titres stipule que ces derniers pr\u00e9sentent un rang de priorit\u00e9 inf\u00e9rieur \u00e0 toute autre dette de premier rang (garantie ou non). En cons\u00e9quence, ces titres ont tendance \u00e0 \u00eatre moins bien not\u00e9s que les obligations de premier rang log\u00e9es dans la m\u00eame structure de capital, la probabilit\u00e9 de recouvrement du capital investi \u00e9tant jug\u00e9e plus faible. Dans les march\u00e9s \u00e9mergents toutefois, il n&rsquo;est pas&#8230;<\/p>\n","protected":false},"author":93,"featured_media":1674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30,7],"tags":[124],"class_list":["post-1659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marches-et-acteurs","category-pays","tag-obligations-de-societes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&#039;est pas correctement \u00e9valu\u00e9 - Francais<\/title>\n<meta name=\"description\" content=\"Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles de Quinsonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/\"},\"author\":{\"name\":\"Charles de Quinsonas\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/d59663f84b4459947ae06d4410e2a255\"},\"headline\":\"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&rsquo;est pas correctement \u00e9valu\u00e9\",\"datePublished\":\"2016-07-20T15:24:31+00:00\",\"dateModified\":\"2023-09-04T15:59:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/\"},\"wordCount\":1459,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/basil-prep1.png\",\"keywords\":[\"obligations de soci\u00e9t\u00e9s\"],\"articleSection\":[\"march\u00e9s et acteurs\",\"Pays\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/\",\"name\":\"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n'est pas correctement \u00e9valu\u00e9 - Francais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/basil-prep1.png\",\"datePublished\":\"2016-07-20T15:24:31+00:00\",\"dateModified\":\"2023-09-04T15:59:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/d59663f84b4459947ae06d4410e2a255\"},\"description\":\"Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/basil-prep1.png\",\"contentUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/basil-prep1.png\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2016\\\/07\\\/le-marche-des-obligations-perpetuelles-bresiliennes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&#8217;est pas correctement \u00e9valu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\",\"name\":\"Francais\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/d59663f84b4459947ae06d4410e2a255\",\"name\":\"Charles de Quinsonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g\",\"caption\":\"Charles de Quinsonas\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/author\\\/charlesdequinsonas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n'est pas correctement \u00e9valu\u00e9 - Francais","description":"Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/","twitter_misc":{"Written by":"Charles de Quinsonas","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/"},"author":{"name":"Charles de Quinsonas","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/d59663f84b4459947ae06d4410e2a255"},"headline":"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&rsquo;est pas correctement \u00e9valu\u00e9","datePublished":"2016-07-20T15:24:31+00:00","dateModified":"2023-09-04T15:59:14+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/"},"wordCount":1459,"commentCount":0,"image":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png","keywords":["obligations de soci\u00e9t\u00e9s"],"articleSection":["march\u00e9s et acteurs","Pays"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/","url":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/","name":"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n'est pas correctement \u00e9valu\u00e9 - Francais","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#primaryimage"},"image":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png","datePublished":"2016-07-20T15:24:31+00:00","dateModified":"2023-09-04T15:59:14+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/d59663f84b4459947ae06d4410e2a255"},"description":"Dans les march\u00e9s d\u00e9velopp\u00e9s, la grande majorit\u00e9 des obligations perp\u00e9tuelles sont contractuellement subordonn\u00e9es. Cela signifie que la documentation","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#primaryimage","url":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png","contentUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/basil-prep1.png","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/francais\/2016\/07\/le-marche-des-obligations-perpetuelles-bresiliennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bondvigilantes.com\/francais\/"},{"@type":"ListItem","position":2,"name":"Le march\u00e9 des obligations perp\u00e9tuelles br\u00e9siliennes n&#8217;est pas correctement \u00e9valu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/francais\/#website","url":"https:\/\/bondvigilantes.com\/francais\/","name":"Francais","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/francais\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/d59663f84b4459947ae06d4410e2a255","name":"Charles de Quinsonas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f45d2254c3dd5975e9cf91fd60201250b40929aa88944e4cdf2a317c5c74b0f3?s=96&d=mm&r=g","caption":"Charles de Quinsonas"},"url":"https:\/\/bondvigilantes.com\/francais\/author\/charlesdequinsonas\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/1659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/comments?post=1659"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/1659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/media\/1674"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/media?parent=1659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/categories?post=1659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/tags?post=1659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}