{"id":2779,"date":"2017-12-15T15:09:59","date_gmt":"2017-12-15T15:09:59","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/francais\/?p=2779"},"modified":"2018-01-02T16:01:45","modified_gmt":"2018-01-02T16:01:45","slug":"golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/","title":{"rendered":"Golaccio ! &#8211; l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives"},"content":{"rendered":"<p>Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier 2010. Abstraction faite du parti pris visc\u00e9ral de deux de mes estim\u00e9s coll\u00e8gues (tous deux italiens et ardents supports du Milan AC), nous avons pris la d\u00e9cision de ne pas investir dans l\u2019\u00e9mission de 300\u00a0millions d\u2019euros d\u2019obligations \u00e0 \u00e9ch\u00e9ance 2022, servant un rendement de 4,875\u00a0%.<\/p>\n<p>Sur le plan des fondamentaux, du droit prioritaire et de la valeur relative, cette \u00e9mission fait plut\u00f4t bonne figure. L\u2019Inter Milan est un club bien implant\u00e9, qui repose sur un large socle de supporters et est actuellement en t\u00eate de la S\u00e9rie\u00a0A (championnat d\u2019Italie). En tant que tel, il r\u00e9unit de nombreuses garanties lui permettant de g\u00e9n\u00e9rer des revenus t\u00e9l\u00e9visuels durables et de d\u00e9velopper sa marque gr\u00e2ce aux recettes de sponsoring. Le risque de performances durablement m\u00e9diocres pouvant peser sur ses revenus semble limit\u00e9, du moins pour l\u2019instant. C\u2019est un facteur important dans la mesure o\u00f9 l\u2019\u00e9mission obligataire est structur\u00e9e de telle sorte que les fonds pr\u00eat\u00e9s par les d\u00e9tenteurs de titres sont nantis sur les flux de tr\u00e9sorerie g\u00e9n\u00e9r\u00e9s gr\u00e2ce aux recettes m\u00e9diatiques et aux accords de sponsoring, et non ceux g\u00e9n\u00e9r\u00e9s par le club dans son ensemble. Fondamentalement, cela \u00e9limine un facteur n\u00e9gatif potentiellement important qui est celui de l\u2019inflation des co\u00fbts que pourrait constituer toute demande de revalorisation salariale de la part des joueurs.<\/p>\n<p>Par ailleurs, le coupon de 4,875\u00a0% semble attractif pour un titre not\u00e9 BB-, surtout par rapport au reste du march\u00e9 obligataire europ\u00e9en \u00e0 haut rendement sur lequel les obligations d\u2019entreprises not\u00e9es BB servent en moyenne entre 1,8\u00a0% et 2,5\u00a0%.<\/p>\n<p>O\u00f9 est donc le probl\u00e8me\u00a0? D\u2019apr\u00e8s nous dans le d\u00e9calage existant entre le profil de maturit\u00e9 de l\u2019obligation et les flux de tr\u00e9sorerie potentiels. Cette derni\u00e8re est en effet assujettie au tableau d\u2019amortissement suivant\u00a0:<\/p>\n<p><strong>Amortissement obligatoire des rachats et date\/montant de remboursement du principal<\/strong><\/p>\n<p>31 d\u00e9cembre 2018 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . 3\u00a0100\u00a0000 \u20ac<\/p>\n<p>30 juin 2019 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . .3\u00a0150\u00a0000 \u20ac<\/p>\n<p>31 d\u00e9cembre 2019 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . 3\u00a0250\u00a0000 \u20ac<\/p>\n<p>30 juin 2020 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . .3\u00a0300\u00a0000 \u20ac<\/p>\n<p>31 d\u00e9cembre 2020 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . 3\u00a0400\u00a0000 \u20ac<\/p>\n<p>30 juin 2021 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . .3\u00a0500\u00a0000 \u20ac<\/p>\n<p>31 d\u00e9cembre 2021 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . 3\u00a0550\u00a0000 \u20ac<\/p>\n<p>30 juin 2022 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . .3\u00a0650\u00a0000 \u20ac<\/p>\n<p>31 d\u00e9cembre 2022 . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . . .273\u00a0100\u00a0000 \u20ac<\/p>\n<p>Dans cette hypoth\u00e8se, l\u2019amortissement semble judicieux mais les montants dont le remboursement est obligatoire semblent d\u00e9risoires par rapport au montant total de l\u2019emprunt. En effet, plus de 270\u00a0millions d\u2019euros sur les 300\u00a0millions de l\u2019\u00e9mission sont remboursables \u00e0 l\u2019\u00e9ch\u00e9ance. Dans le m\u00eame temps, si le club respecte certains crit\u00e8res financiers, tout exc\u00e9dent de tr\u00e9sorerie g\u00e9n\u00e9r\u00e9 par les droits de diffusion et les redevances m\u00e9diatiques peut \u00eatre distribu\u00e9 \u00e0 d\u2019autres entit\u00e9s sur lesquelles les d\u00e9tenteurs d\u2019obligations n\u2019ont aucun recours juridique. Si l&rsquo;on pousse la logique \u00e0 l\u2019extr\u00eame, cela pourrait signifier que la structure est en mesure de se r\u00e9endetter sur toute la dur\u00e9e de vie de l\u2019\u00e9mission en augmentant les risques de refinancement de cr\u00e9dit, et ce, m\u00eame si le club r\u00e9alise de bonnes performances et mon\u00e9tise son succ\u00e8s.<\/p>\n<p>Par cons\u00e9quent, si l\u2019Inter est incontestablement le meilleur club milanais \u00e0 l\u2019heure actuelle, nous restons convaincus que ce sont les d\u00e9tails qui comptent s\u2019agissant de sa premi\u00e8re \u00e9mission obligataire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier 2010. Abstraction faite du parti pris visc\u00e9ral de deux de mes estim\u00e9s coll\u00e8gues (tous deux italiens et ardents supports du Milan AC), nous avons pris la d\u00e9cision de ne pas investir dans l\u2019\u00e9mission de 300\u00a0millions d\u2019euros d\u2019obligations \u00e0 \u00e9ch\u00e9ance 2022, servant un rendement de 4,875\u00a0%. Sur le plan des fondamentaux, du droit prioritaire et de la valeur relative, cette&#8230;<\/p>\n","protected":false},"author":62,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[213],"class_list":["post-2779","post","type-post","status-publish","format-standard","hentry","category-categories-obligataires","tag-marche-europeen-a-haut-rendement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Golaccio ! - l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives - Francais<\/title>\n<meta name=\"description\" content=\"Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Tomlins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/\"},\"author\":{\"name\":\"James Tomlins\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/191e5927bd1b373f71f0eb68646d0f9f\"},\"headline\":\"Golaccio ! &#8211; l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives\",\"datePublished\":\"2017-12-15T15:09:59+00:00\",\"dateModified\":\"2018-01-02T16:01:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/\"},\"wordCount\":584,\"commentCount\":0,\"keywords\":[\"March\u00e9 europ\u00e9en \u00e0 haut rendement\"],\"articleSection\":[\"cat\u00e9gories obligataires\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/\",\"name\":\"Golaccio ! - l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives - Francais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\"},\"datePublished\":\"2017-12-15T15:09:59+00:00\",\"dateModified\":\"2018-01-02T16:01:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/191e5927bd1b373f71f0eb68646d0f9f\"},\"description\":\"Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2017\\\/12\\\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Golaccio ! &#8211; l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\",\"name\":\"Francais\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/191e5927bd1b373f71f0eb68646d0f9f\",\"name\":\"James Tomlins\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g\",\"caption\":\"James Tomlins\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/author\\\/jamestomlins\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Golaccio ! - l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives - Francais","description":"Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/","twitter_misc":{"Written by":"James Tomlins","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/"},"author":{"name":"James Tomlins","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/191e5927bd1b373f71f0eb68646d0f9f"},"headline":"Golaccio ! &#8211; l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives","datePublished":"2017-12-15T15:09:59+00:00","dateModified":"2018-01-02T16:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/"},"wordCount":584,"commentCount":0,"keywords":["March\u00e9 europ\u00e9en \u00e0 haut rendement"],"articleSection":["cat\u00e9gories obligataires"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/","url":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/","name":"Golaccio ! - l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives - Francais","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/#website"},"datePublished":"2017-12-15T15:09:59+00:00","dateModified":"2018-01-02T16:01:45+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/191e5927bd1b373f71f0eb68646d0f9f"},"description":"Hier, le club lombard a proc\u00e9d\u00e9 \u00e0 la premi\u00e8re \u00e9mission de titres \u00e0 haut rendement depuis que Manchester United s\u2019est financ\u00e9 sur les march\u00e9s en janvier","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/francais\/2017\/12\/golaccio-linter-milan-annonce-lemission-dobligations-europeennes-speculatives\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bondvigilantes.com\/francais\/"},{"@type":"ListItem","position":2,"name":"Golaccio ! &#8211; l\u2019Inter Milan annonce l\u2019\u00e9mission d\u2019obligations europ\u00e9ennes sp\u00e9culatives"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/francais\/#website","url":"https:\/\/bondvigilantes.com\/francais\/","name":"Francais","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/francais\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/191e5927bd1b373f71f0eb68646d0f9f","name":"James Tomlins","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c12d8288a434682928f2137cbe0cd4dfe037e9ef16454e1fbfe43cc8cc081d?s=96&d=mm&r=g","caption":"James Tomlins"},"url":"https:\/\/bondvigilantes.com\/francais\/author\/jamestomlins\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/2779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/comments?post=2779"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/2779\/revisions"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/media?parent=2779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/categories?post=2779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/tags?post=2779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}