{"id":3610,"date":"2018-12-03T09:00:25","date_gmt":"2018-12-03T09:00:25","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/francais\/?p=3610"},"modified":"2018-12-06T12:09:33","modified_gmt":"2018-12-06T12:09:33","slug":"panoramic-weekly-fed-extends-goldilocks-contract","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/","title":{"rendered":"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb"},"content":{"rendered":"<p>Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour offrir un coup de pouce aux b\u00e9n\u00e9fices, mais pas trop pour justifier de fortes hausses des taux, beaucoup s\u2019attendaient \u00e0 une ann\u00e9e 2018 moins favorable et marqu\u00e9e par un important cycle de rel\u00e8vement des taux &#8211; jusqu\u2019\u00e0 la semaine derni\u00e8re. Le pr\u00e9sident de la Fed am\u00e9ricaine, Jerome Powell, a d\u00e9clar\u00e9 que le taux directeur actuel se situait tout juste en dessous du taux non acc\u00e9l\u00e9rateur d\u2019inflation &#8211; un signe que la Banque centrale pourrait ralentir la trajectoire haussi\u00e8re de ses taux qu\u2019elle avait indiqu\u00e9e en octobre. Les actions se sont fortement appr\u00e9ci\u00e9es et les rendements obligataires ont recul\u00e9 ; le rendement de l\u2019emprunt d\u2019\u00c9tat am\u00e9ricain \u00e0 10 ans est tomb\u00e9 sous la barre des 3 % pour la premi\u00e8re fois depuis septembre. Les spreads des actifs risqu\u00e9s, comme ceux des obligations \u00e0 haut rendement, se sont contract\u00e9s.<\/p>\n<p>Les propos accommodants de Jerome Powell sont intervenus alors m\u00eame que le prix du p\u00e9trole a chut\u00e9 de 20 dollars au cours des deux derniers mois pour s\u2019\u00e9tablir l\u00e9g\u00e8rement au-dessus de 50 dollars le baril, son plus bas niveau en plus d\u2019un an. Les statistiques \u00e9conomiques aux \u00c9tats-Unis ont \u00e9galement d\u00e9\u00e7u (logement, production industrielle, ventes de biens durables et confiance des m\u00e9nages). Le revers du pr\u00e9sident am\u00e9ricain Trump \u00e0 l\u2019issue des r\u00e9centes \u00e9lections de mi-mandat rend plus improbables de nouvelles baisses d\u2019imp\u00f4t, ce qui pourrait peser sur la croissance. La semaine derni\u00e8re, les indices PMI europ\u00e9ens sont \u00e9galement ressortis inf\u00e9rieurs aux attentes.<a href=\"https:\/\/blogs.imf.org\/2021\/12\/28\/g20-step-up-to-boost-inclusive-growth\/?utm_medium=email&amp;utm_source=govdelivery\" target=\"_blank\" rel=\"noopener\"><strong> Le FMI a mis en garde contre la d\u00e9t\u00e9rioration des statistiques au niveau mondial et l\u2019apparition de nuages plus sombres, un mois seulement apr\u00e8s avoir r\u00e9duit ses pr\u00e9visions de croissance mondiale<\/strong><\/a><strong>.<\/strong> Au moins, les tensions g\u00e9opolitiques ont sembl\u00e9 s\u2019apaiser apr\u00e8s le sommet du G20 qui s\u2019est tenu ce week-end \u00e0 Buenos Aires. A cette occasion, Donald Trump et le Pr\u00e9sident chinois Xi Jinping ont sign\u00e9 une tr\u00eave dans leur guerre commerciale, laquelle a contribu\u00e9 \u00e0 affaiblir le dollar am\u00e9ricain et, ce faisant, \u00e0 soutenir les actifs des march\u00e9s \u00e9mergents.<\/p>\n<h2><strong>En hausse\u00a0:<\/strong><\/h2>\n<p><strong>Devises \u00e9mergentes &#8211; soleil d\u2019hiver :<\/strong> les devises \u00e9mergentes ont connu un bon mois de novembre. En d\u00e9pit de la r\u00e9cente baisse des march\u00e9s du cr\u00e9dit, les obligations souveraines \u00e9mergentes libell\u00e9es en devise locale ont offert aux investisseurs une performance de 1,6 % en novembre, laquelle s\u2019\u00e9tablit \u00e0 2,2 % une fois convertie en dollar am\u00e9ricain sous l\u2019effet de l\u2019appr\u00e9ciation de la devise. Comme l\u2019illustre le graphique, la lire turque (ligne bleue) s\u2019est sensiblement appr\u00e9ci\u00e9e de 6,7 % face au billet vert jusqu\u2019\u00e0 pr\u00e9sent ce mois-ci, regagnant ainsi pr\u00e8s de la moiti\u00e9 du terrain qu\u2019elle avait conc\u00e9d\u00e9 durant l\u2019\u00e9t\u00e9. Les investisseurs semblent d\u00e9sormais moins pr\u00e9occup\u00e9s par les fondamentaux de la Turquie, surtout compte tenu de la chute du prix du p\u00e9trole qui ne manque pas d\u2019aider la balance courante du pays. L\u2019Inde, un autre grand pays importateur de p\u00e9trole, a vu sa devise fortement s\u2019appr\u00e9cier de 5 % au cours du mois dernier, d\u2019autant plus que les \u00c9tats-Unis ont lev\u00e9 certaines sanctions contre l\u2019Iran afin que le pays producteur de p\u00e9trole puisse continuer \u00e0 exporter. Le rand sud-africain, r\u00e9cemment d\u00e9laiss\u00e9 par les investisseurs en raison des d\u00e9ficits budg\u00e9taire et de la balance courante \u00e9lev\u00e9s du pays, s\u2019est \u00e9galement redress\u00e9 apr\u00e8s que la banque centrale ait r\u00e9cemment relev\u00e9 ses taux de 6,50 % \u00e0 6,75 % et abaiss\u00e9 ses pr\u00e9visions d\u2019inflation. Apr\u00e8s la temp\u00eate de l\u2019\u00e9t\u00e9 durant laquelle l\u2019incertitude entourant la Turquie et l\u2019Argentine a gagn\u00e9 d\u2019autres pays \u00e9mergents, les investisseurs semblent prendre du recul sur les fondamentaux. Comme le montre le graphique, les perspectives de croissance sont beaucoup plus prometteuses pour les pays \u00e9mergents que pour les pays d\u00e9velopp\u00e9s.<\/p>\n<p><a href=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\" data-rel=\"lightbox-gallery-3idnVA6e\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3614\" src=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png 960w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF-300x225.png 300w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><strong>Italie &#8211; les derniers seront les premiers :<\/strong> toujours nettement dans le rouge depuis le d\u00e9but de l\u2019ann\u00e9e, les emprunts d\u2019\u00c9tat italiens occupent une surprenante premi\u00e8re place dans le tableau des performances hebdomadaires des 100 classes d\u2019actifs obligataires. Ces gains, qui permettent de ramener la baisse depuis le d\u00e9but de l\u2019ann\u00e9e \u00e0 4,7 %, interviennent au moment o\u00f9 le gouvernement italien et l\u2019UE semblent se rapprocher d\u2019un accord sur le d\u00e9ficit budg\u00e9taire de l\u2019Italie. Depuis son \u00e9lection en mai, le gouvernement a d\u00e9fi\u00e9 la rigueur budg\u00e9taire de Bruxelles, cr\u00e9ant ainsi des tensions qui ont non seulement conduit \u00e0 un \u00e9largissement des spreads des emprunts d\u2019\u00c9tat et des obligations d\u2019entreprises, mais ont \u00e9galement eu un impact n\u00e9gatif sur les actifs europ\u00e9ens en g\u00e9n\u00e9ral. Le regain d\u2019optimisme au sujet d\u2019un accord a permis d\u2019am\u00e9liorer cette semaine les performances des indices \u00e0 haut rendement europ\u00e9ens o\u00f9 l\u2019Italie a un poids de 15 %, plus que toute autre nation.<\/p>\n<h2><strong>En baisse\u00a0:<\/strong><\/h2>\n<p><strong>Les voitures &#8211; le canari dans la mine de charbon ?<\/strong> Les ventes de voitures ont cess\u00e9 d\u2019\u00eatre un moteur de l\u2019\u00e9conomie &#8211; elles ressemblent plus \u00e0 une crevaison dans les pneus de la croissance mondiale : peut-\u00eatre est-ce en raison des guerres commerciales mondiales, ou du vieillissement des populations et du recours par les jeunes aux services \u00e0 la demande dans les pays d\u00e9velopp\u00e9s, ou de l\u2019instauration par l\u2019UE de nouvelles mesures concernant les \u00e9missions polluantes. Comme le r\u00e9v\u00e8le le graphique, la croissance annualis\u00e9e des ventes mondiales de voitures est en train de s\u2019enfoncer en territoire n\u00e9gatif, une situation qui contribue \u00e0 faire de ce secteur le moins performant du march\u00e9 \u00e0 haut rendement am\u00e9ricain depuis le d\u00e9but de l\u2019ann\u00e9e avec une baisse de 7,3 %. Plus t\u00f4t cette semaine, le g\u00e9ant de l\u2019automobile GM a annonc\u00e9 qu\u2019il pr\u00e9voyait de fermer jusqu\u2019\u00e0 cinq usines en Am\u00e9rique du Nord et de r\u00e9duire son personnel. Pour empirer encore un peu plus les choses, le FMI n\u2019entrevoit pas d\u2019am\u00e9lioration \u00e0 venir &#8211; il s\u2019attend \u00e0 un ralentissement de la croissance, surtout dans les \u00e9conomies d\u00e9velopp\u00e9es en raison du vieillissement de la population, de la faiblesse de la productivit\u00e9 et de la hausse des taux. Aux \u00c9tats-Unis, la fin des r\u00e9centes mesures de relance budg\u00e9taire pourrait \u00e9galement freiner la croissance. Les investisseurs \u00e0 haut rendement semblent avoir anticip\u00e9 les temps difficiles \u00e0 venir : les secteurs plus r\u00e9sistants des supermarch\u00e9s et de la pharmacie constituent les plus performants du march\u00e9 \u00e0 haut rendement cette ann\u00e9e avec des hausses de 7,8 % et 6,7 %.<\/p>\n<p><a href=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/4\/2021\/12\/2-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\" data-rel=\"lightbox-gallery-3idnVA6e\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3615\" src=\"https:\/\/bondvigilantes.com\/wp-content\/uploads\/sites\/4\/2021\/12\/2-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/2-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png 960w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/2-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF-300x225.png 300w, https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/2-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><strong>TIPS \u2013 si inint\u00e9ressants que cela ?<\/strong> Les titres index\u00e9s sur l\u2019inflation du Tr\u00e9sor am\u00e9ricain (TIPS) ont recul\u00e9 de 0,6 % au cours des cinq derni\u00e8res s\u00e9ances, portant ainsi leur baisse \u00e0 2,7 % depuis le d\u00e9but de l\u2019ann\u00e9e. Cette baisse a principalement \u00e9t\u00e9 due \u00e0 la chute du prix du p\u00e9trole et au caract\u00e8re d\u00e9cevant des statistiques. Pour autant, certains investisseurs font valoir qu\u2019avec un rendement nominal \u00e0 10 ans de 3,0 % et un point mort d\u2019inflation (ou les anticipations inflationnistes) \u00e0 10 ans de 1,93 % aux \u00c9tats-Unis, un taux r\u00e9el de plus de 1 % est int\u00e9ressant par rapport aux taux r\u00e9els n\u00e9gatifs qui pr\u00e9valent encore dans la plupart des pays d\u00e9velopp\u00e9s o\u00f9 l\u2019inflation est sup\u00e9rieure au taux directeur de base.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour offrir un coup de pouce aux b\u00e9n\u00e9fices, mais pas trop pour justifier de fortes hausses des taux, beaucoup s\u2019attendaient \u00e0 une ann\u00e9e 2018 moins favorable et marqu\u00e9e par un important cycle de rel\u00e8vement des taux &#8211; jusqu\u2019\u00e0 la semaine derni\u00e8re. Le pr\u00e9sident de la Fed am\u00e9ricaine, Jerome Powell, a d\u00e9clar\u00e9 que le taux directeur actuel se situait tout juste en dessous du taux&#8230;<\/p>\n","protected":false},"author":141,"featured_media":3614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[301,13],"tags":[52,134],"class_list":["post-3610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fed","category-taux-dinteret","tag-banques-centrales","tag-taux-dinteret"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb - Francais<\/title>\n<meta name=\"description\" content=\"Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena Moya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/\"},\"author\":{\"name\":\"Elena Moya\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/14a66b370f91b8c5210d6967cdb26e4c\"},\"headline\":\"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb\",\"datePublished\":\"2018-12-03T09:00:25+00:00\",\"dateModified\":\"2018-12-06T12:09:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/\"},\"wordCount\":1296,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\",\"keywords\":[\"banques centrales\",\"Taux d'int\u00e9r\u00eat\"],\"articleSection\":[\"FED\",\"Taux d'int\u00e9r\u00eat\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/\",\"name\":\"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb - Francais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\",\"datePublished\":\"2018-12-03T09:00:25+00:00\",\"dateModified\":\"2018-12-06T12:09:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/14a66b370f91b8c5210d6967cdb26e4c\"},\"description\":\"Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\",\"contentUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/2018\\\/12\\\/panoramic-weekly-fed-extends-goldilocks-contract\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/\",\"name\":\"Francais\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/#\\\/schema\\\/person\\\/14a66b370f91b8c5210d6967cdb26e4c\",\"name\":\"Elena Moya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g\",\"caption\":\"Elena Moya\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/francais\\\/author\\\/elenamoya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb - Francais","description":"Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/","twitter_misc":{"Written by":"Elena Moya","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/"},"author":{"name":"Elena Moya","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/14a66b370f91b8c5210d6967cdb26e4c"},"headline":"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb","datePublished":"2018-12-03T09:00:25+00:00","dateModified":"2018-12-06T12:09:33+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/"},"wordCount":1296,"commentCount":0,"image":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png","keywords":["banques centrales","Taux d'int\u00e9r\u00eat"],"articleSection":["FED","Taux d'int\u00e9r\u00eat"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/","url":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/","name":"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb - Francais","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/francais\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#primaryimage"},"image":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png","datePublished":"2018-12-03T09:00:25+00:00","dateModified":"2018-12-06T12:09:33+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/14a66b370f91b8c5210d6967cdb26e4c"},"description":"Si les investisseurs ont profit\u00e9 d\u2019un sc\u00e9nario \u00ab\u00a0id\u00e9al\u00a0\u00bb en 2017, ann\u00e9e au cours de laquelle la croissance s\u2019est av\u00e9r\u00e9e suffisamment vigoureuse pour","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#primaryimage","url":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png","contentUrl":"https:\/\/bondvigilantes.com\/francais\/wp-content\/uploads\/sites\/4\/2021\/12\/1-fr-P18-12-003-Panoramic-Weekly-Fed-extends-Goldilocks-contract.FR-VF.png","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/francais\/2018\/12\/panoramic-weekly-fed-extends-goldilocks-contract\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bondvigilantes.com\/francais\/"},{"@type":"ListItem","position":2,"name":"Panorama hebdomadaire: la Fed prolonge les conditions \u00ab id\u00e9ales \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/francais\/#website","url":"https:\/\/bondvigilantes.com\/francais\/","name":"Francais","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/francais\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/francais\/#\/schema\/person\/14a66b370f91b8c5210d6967cdb26e4c","name":"Elena Moya","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55828bf73a4d57705fa5b0edb2298863175179cd3223e4309435e4f9d54bcdbe?s=96&d=mm&r=g","caption":"Elena Moya"},"url":"https:\/\/bondvigilantes.com\/francais\/author\/elenamoya\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/3610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/comments?post=3610"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/posts\/3610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/media\/3614"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/media?parent=3610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/categories?post=3610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/francais\/wp-json\/wp\/v2\/tags?post=3610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}