{"id":1297,"date":"2013-05-28T08:28:28","date_gmt":"2013-05-28T08:28:28","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/italiano\/?p=1297"},"modified":"2013-05-28T08:28:28","modified_gmt":"2013-05-28T08:28:28","slug":"altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/","title":{"rendered":"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo"},"content":{"rendered":"<p>Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli investitori nipponici. Siamo sicuri che un investitore giapponese accorto lascerebbe da parte i titoli nazionali per evitare l\u2019impatto del cambio e le conseguenze devastanti dell\u2019inflazione, o per lo meno per cercare di ottenere rendimenti pi\u00f9 elevati rispetto ai risicati guadagni (contenuti artificialmente) offerti dai titoli di Stato?<\/p>\n<p>Beh, di sicuro non si sono buttati sui titoli in valuta estera, anzi, stanno facendo esattamente l\u2019opposto. All\u2019inizio del mese i media hanno dato ampio risalto alla notizia che gli investitori giapponesi erano stati acquirenti netti di bond esteri nelle tre settimane al 10 maggio. Tuttavia i dati diffusi fra ieri e oggi indicano che nella settimana conclusa il 17 maggio gli operatori nipponici hanno venduto obbligazioni estere per JPY 804,4 miliardi netti, annullando completamente gli acquisti delle settimane precedenti.<\/p>\n<p>Il grafico seguente mostra gli acquisti netti settimanali di obbligazioni in valuta estera di grandi investitori come banche ed istituti di credito, compagnie di assicurazione, societ\u00e0 di asset management ecc. La linea blu, che rappresenta la media mobile a tre mesi, segnala che i rimborsi di emissioni estere richiesti dagli operatori giapponesi sono prossimi al livello massimo dall\u2019inizio della rilevazione del dato nel 2001.<\/p>\n<p><a href=\"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1304\" alt=\"1\" src=\"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png\" width=\"957\" height=\"718\" \/><\/a><\/p>\n<p>Anche se \u00e8 difficile trarre conclusioni, sembra che il rally del Nikkei, la flessione dello yen e il rimbalzo dei titoli governativi dei Paesi semi-core dell\u2019area euro sia stato indotto da investitori stranieri intenzionati ad anticipare qualcosa che tuttavia non si \u00e8 ancora verificata. \u00c8 vero che i giapponesi potrebbero ancora fuggire dal loro mercato domestico, ma affinch\u00e9 ci\u00f2 accada, \u00e8 necessario che le aspettative sull\u2019inflazione degli investitori, attualmente gi\u00e0 elevate, si rializzino: il mercato obbligazionario sconta un livello medio dell\u2019inflazione nipponica dell\u20191,8% annuo per i prossimi 5 anni, nonostante il QE in Giappone come in altri Stati non sia stato sinora garanzia di accelerazione dell\u2019inflazione o di indebolimento delle valute. Forse la situazione sarebbe diversa se venissero riviste le elevate commissioni addebitate ai grandi investitori nipponici che vogliono impiegare capitali all\u2019estero, ma anche in questo caso i costi di finanziamento e le esigenze di copertura farebbero convergere i giapponesi verso il mercato interno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli investitori nipponici. Siamo sicuri che un investitore giapponese accorto lascerebbe da parte i titoli nazionali per evitare l\u2019impatto del cambio e le conseguenze devastanti dell\u2019inflazione, o per lo meno per cercare di ottenere rendimenti pi\u00f9 elevati rispetto ai risicati guadagni (contenuti artificialmente) offerti dai titoli di Stato? Beh, di sicuro non si sono buttati sui titoli in valuta estera, anzi,&#8230;<\/p>\n","protected":false},"author":189,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20,8],"tags":[54,222],"class_list":["post-1297","post","type-post","status-publish","format-standard","hentry","category-macro-e-politica","category-paesi","tag-giappone","tag-macro-e-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo - Italian<\/title>\n<meta name=\"description\" content=\"Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Riddell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/\"},\"author\":{\"name\":\"Mike Riddell\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/5c62529eb1af96b2949e1eaf4e0c65bc\"},\"headline\":\"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo\",\"datePublished\":\"2013-05-28T08:28:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/\"},\"wordCount\":382,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/15.png\",\"keywords\":[\"Giappone\",\"Macro e Politica\"],\"articleSection\":[\"Macro e Politica\",\"Paesi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/\",\"name\":\"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo - Italian\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/15.png\",\"datePublished\":\"2013-05-28T08:28:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/5c62529eb1af96b2949e1eaf4e0c65bc\"},\"description\":\"Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/15.png\",\"contentUrl\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/15.png\",\"width\":957,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2013\\\/05\\\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\",\"name\":\"Italian\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/5c62529eb1af96b2949e1eaf4e0c65bc\",\"name\":\"Mike Riddell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g\",\"caption\":\"Mike Riddell\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/author\\\/mikeriddellnew\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo - Italian","description":"Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/","twitter_misc":{"Written by":"Mike Riddell","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/"},"author":{"name":"Mike Riddell","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/5c62529eb1af96b2949e1eaf4e0c65bc"},"headline":"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo","datePublished":"2013-05-28T08:28:28+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/"},"wordCount":382,"commentCount":0,"image":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png","keywords":["Giappone","Macro e Politica"],"articleSection":["Macro e Politica","Paesi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/","url":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/","name":"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo - Italian","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#primaryimage"},"image":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#primaryimage"},"thumbnailUrl":"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png","datePublished":"2013-05-28T08:28:28+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/5c62529eb1af96b2949e1eaf4e0c65bc"},"description":"Uno dei temi di investimento che ha trainato le piazze finanziarie globali negli ultimi mesi \u00e8 l\u2019acquisto di asset in valuta estera da parte degli","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#primaryimage","url":"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png","contentUrl":"https:\/\/bondvigilantes.com\/italiano\/wp-content\/uploads\/sites\/2\/2021\/12\/15.png","width":957,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/italiano\/2013\/05\/altro-che-comprare-obbligazioni-in-valuta-estera-i-giapponesi-stanno-vendendo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bondvigilantes.com\/italiano\/"},{"@type":"ListItem","position":2,"name":"Altro che comprare obbligazioni in valuta estera, i giapponesi stanno vendendo"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/italiano\/#website","url":"https:\/\/bondvigilantes.com\/italiano\/","name":"Italian","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/italiano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/5c62529eb1af96b2949e1eaf4e0c65bc","name":"Mike Riddell","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28bee3ffcdd030a5c1f55b86da8deb803dc8ed02437550a76dae159a2870b3d2?s=96&d=mm&r=g","caption":"Mike Riddell"},"url":"https:\/\/bondvigilantes.com\/italiano\/author\/mikeriddellnew\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/comments?post=1297"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/1297\/revisions"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/categories?post=1297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/tags?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}