{"id":4399,"date":"2017-06-19T07:40:17","date_gmt":"2017-06-19T07:40:17","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/italiano\/?p=4399"},"modified":"2017-06-19T08:04:26","modified_gmt":"2017-06-19T08:04:26","slug":"bvtv-will-fed-spoil-em-party","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/","title":{"rendered":"Questa settimana su BVTV"},"content":{"rendered":"<p>Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi principali sul mercato ad oggi con uno sguardo agli avvenimenti della prossima settimana.<\/p>\n<p>Si noti che il video \u00e8 in inglese.<\/p>\n<p id=\"buto_JFpCN\" class=\"video\" style=\"width: 100%; height: 345px;\">\u00a0<\/p>\n<p><script>(function(d, config) {var script = d.createElement(\"script\");\n                script.setAttribute(\"async\", true);\n                var data = JSON.stringify(config);\n                script.src = \"\/\/js.buto.tv\/video\/\" + data;\n                var s = d.getElementsByTagName(\"script\")[0];\n                s.parentNode.insertBefore(script, s)\n            })(document, {\"object_id\":\"JFpCN\", \"width\":\"425px\"})<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi principali sul mercato ad oggi con uno sguardo agli avvenimenti della prossima settimana. Si noti che il video \u00e8 in inglese. \u00a0<\/p>\n","protected":false},"author":107,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[],"class_list":["post-4399","post","type-post","status-publish","format-standard","hentry","category-bvtv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Questa settimana su BVTV - Italian<\/title>\n<meta name=\"description\" content=\"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Eisenegger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/\"},\"author\":{\"name\":\"Mario Eisenegger\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\"},\"headline\":\"Questa settimana su BVTV\",\"datePublished\":\"2017-06-19T07:40:17+00:00\",\"dateModified\":\"2017-06-19T08:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/\"},\"wordCount\":48,\"commentCount\":0,\"articleSection\":[\"BVTV\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/\",\"name\":\"Questa settimana su BVTV - Italian\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\"},\"datePublished\":\"2017-06-19T07:40:17+00:00\",\"dateModified\":\"2017-06-19T08:04:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\"},\"description\":\"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2017\\\/06\\\/bvtv-will-fed-spoil-em-party\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questa settimana su BVTV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\",\"name\":\"Italian\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\",\"name\":\"Mario Eisenegger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"caption\":\"Mario Eisenegger\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/author\\\/marioeisenegger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Questa settimana su BVTV - Italian","description":"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/","twitter_misc":{"Written by":"Mario Eisenegger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/"},"author":{"name":"Mario Eisenegger","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8"},"headline":"Questa settimana su BVTV","datePublished":"2017-06-19T07:40:17+00:00","dateModified":"2017-06-19T08:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/"},"wordCount":48,"commentCount":0,"articleSection":["BVTV"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/","url":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/","name":"Questa settimana su BVTV - Italian","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#website"},"datePublished":"2017-06-19T07:40:17+00:00","dateModified":"2017-06-19T08:04:26+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8"},"description":"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, Mario Eisenegger e Claudia Calich analizzano alcuni dei temi","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/italiano\/2017\/06\/bvtv-will-fed-spoil-em-party\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bondvigilantes.com\/italiano\/"},{"@type":"ListItem","position":2,"name":"Questa settimana su BVTV"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/italiano\/#website","url":"https:\/\/bondvigilantes.com\/italiano\/","name":"Italian","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/italiano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8","name":"Mario Eisenegger","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","caption":"Mario Eisenegger"},"url":"https:\/\/bondvigilantes.com\/italiano\/author\/marioeisenegger\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/4399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/comments?post=4399"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/4399\/revisions"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/media?parent=4399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/categories?post=4399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/tags?post=4399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}