{"id":5046,"date":"2018-06-04T10:21:55","date_gmt":"2018-06-04T10:21:55","guid":{"rendered":"https:\/\/www.bondvigilantes.com\/italiano\/?p=5046"},"modified":"2018-06-04T10:23:29","modified_gmt":"2018-06-04T10:23:29","slug":"bvtv-high-drama-for-italian-high-yield","status":"publish","type":"post","link":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/","title":{"rendered":"Questa settimana su BVTV"},"content":{"rendered":"<p>Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi principali sul mercato ad oggi con uno sguardo agli avvenimenti della prossima settimana.<\/p>\n<p>Si noti che il video \u00e8 in inglese.<\/p>\n<style>\n      .buto_container {\n        position: relative;\n        width: 95%;\n        padding-bottom: 35px;\n        margin-left: 2.5%;\n      }\n\n      .buto_container .base-akita-container {\n        width: 100% !important;\n        height: 100% !important;\n        position: absolute !important;\n      }\n\n      .dl_link {\n        margin-left: 2.5%;\n        margin-top: 20px;\n      }\n\n      .dl_link a {\n        display: block:\n      }\n\n      .dl_link i {\n        margin-left: 5px;\n        display: inline-block;\n      }\n\n    <\/style><div class=\"buto_container\">\n  <div id=\"buto_VfXxm\"><\/div>\n<\/div><div class=\"dl_link\">\n      <a class=\"btn\" href=\"https:\/\/fwd.buto.tv\/videos\/source_file\/mp3\/128\/VfXxm\" target=\"blank\">\n        Download the audio <i class=\"fa fa-volume-up\"><\/i>\n      <\/a>\n    <\/div><script>(function(d,config){var script=d.createElement(\"script\");script.setAttribute(\"async\",true);var data=JSON.stringify(config);script.src=\"\/\/js.buto.tv\/video\/\"+data;var s=d.getElementsByTagName(\"script\")[0];s.parentNode.insertBefore(script,s)})(document,{\"object_id\":\"VfXxm\",\"width\":\"640px\",\"height\":\"360px\"})<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi principali sul mercato ad oggi con uno sguardo agli avvenimenti della prossima settimana. Si noti che il video \u00e8 in inglese.<\/p>\n","protected":false},"author":107,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[257],"tags":[],"class_list":["post-5046","post","type-post","status-publish","format-standard","hentry","category-bvtv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Questa settimana su BVTV - Italian<\/title>\n<meta name=\"description\" content=\"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Eisenegger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/\"},\"author\":{\"name\":\"Mario Eisenegger\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\"},\"headline\":\"Questa settimana su BVTV\",\"datePublished\":\"2018-06-04T10:21:55+00:00\",\"dateModified\":\"2018-06-04T10:23:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/\"},\"wordCount\":49,\"commentCount\":0,\"articleSection\":[\"BVTV\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/\",\"name\":\"Questa settimana su BVTV - Italian\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\"},\"datePublished\":\"2018-06-04T10:21:55+00:00\",\"dateModified\":\"2018-06-04T10:23:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\"},\"description\":\"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/2018\\\/06\\\/bvtv-high-drama-for-italian-high-yield\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questa settimana su BVTV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#website\",\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/\",\"name\":\"Italian\",\"description\":\"M&amp;G\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/#\\\/schema\\\/person\\\/373ae74798e4406641c6ba2da1fa57f8\",\"name\":\"Mario Eisenegger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g\",\"caption\":\"Mario Eisenegger\"},\"url\":\"https:\\\/\\\/bondvigilantes.com\\\/italiano\\\/author\\\/marioeisenegger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Questa settimana su BVTV - Italian","description":"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/","twitter_misc":{"Written by":"Mario Eisenegger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/#article","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/"},"author":{"name":"Mario Eisenegger","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8"},"headline":"Questa settimana su BVTV","datePublished":"2018-06-04T10:21:55+00:00","dateModified":"2018-06-04T10:23:29+00:00","mainEntityOfPage":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/"},"wordCount":49,"commentCount":0,"articleSection":["BVTV"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/","url":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/","name":"Questa settimana su BVTV - Italian","isPartOf":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#website"},"datePublished":"2018-06-04T10:21:55+00:00","dateModified":"2018-06-04T10:23:29+00:00","author":{"@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8"},"description":"Bentornati al nostro aggiornamento settimanale sui mercati obbligazionari. Questo luned\u00ec, James Tomlins\u00a0e Mario Eisenegger analizzano alcuni dei temi","breadcrumb":{"@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bondvigilantes.com\/italiano\/2018\/06\/bvtv-high-drama-for-italian-high-yield\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bondvigilantes.com\/italiano\/"},{"@type":"ListItem","position":2,"name":"Questa settimana su BVTV"}]},{"@type":"WebSite","@id":"https:\/\/bondvigilantes.com\/italiano\/#website","url":"https:\/\/bondvigilantes.com\/italiano\/","name":"Italian","description":"M&amp;G","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bondvigilantes.com\/italiano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/bondvigilantes.com\/italiano\/#\/schema\/person\/373ae74798e4406641c6ba2da1fa57f8","name":"Mario Eisenegger","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e5663d5ab99373ed8a792656acdbfbe8dc8a16c24a617e92f2c99d193d5d282?s=96&d=mm&r=g","caption":"Mario Eisenegger"},"url":"https:\/\/bondvigilantes.com\/italiano\/author\/marioeisenegger\/"}]}},"_links":{"self":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/5046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/comments?post=5046"}],"version-history":[{"count":0,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/posts\/5046\/revisions"}],"wp:attachment":[{"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/media?parent=5046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/categories?post=5046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bondvigilantes.com\/italiano\/wp-json\/wp\/v2\/tags?post=5046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}